{"id":7538,"date":"2026-03-04T12:20:00","date_gmt":"2026-03-04T12:20:00","guid":{"rendered":"https:\/\/educaedtech.foundation\/moocs\/conociendo-jjc\/"},"modified":"2026-03-04T12:20:00","modified_gmt":"2026-03-04T12:20:00","slug":"conociendo-jjc","status":"publish","type":"mooc_course","link":"https:\/\/educaedtech.foundation\/en\/moocs\/conociendo-jjc\/","title":{"rendered":"Conociendo JJC"},"content":{"rendered":"<p>Este curso te ofrece la oportunidad de sumergirte en la<strong> cultura y valores de JJC<\/strong>, as\u00ed como en sus <strong>sistemas de gesti\u00f3n y pol\u00edticas<\/strong>. Aprender\u00e1s sobre los <strong>programas de desarrollo y bienestar<\/strong> que la empresa promueve, lo que te permitir\u00e1 comprender mejor el entorno laboral al que te enfrentas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El curso Conociendo JJC est\u00e1 dirigido a empleados de JJC Grupo que desean ampliar sus conocimientos sobre la empresa y su funcionamiento. Este programa de formaci\u00f3n permite lograr una comprensi\u00f3n m\u00e1s profunda de la cultura y los valores de JJC Grupo. A trav\u00e9s de una video lecci\u00f3n amena y accesible, se fomentar\u00e1 un aprendizaje enriquecedor para todos los participantes.<\/p>","protected":false},"featured_media":0,"template":"","mooc_category":[40,135,136],"class_list":["post-7538","mooc_course","type-mooc_course","status-publish","hentry","mooc_category-group-corporativo","mooc_category-area-35","mooc_category-academy-1182"],"acf":[],"_links":{"self":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/mooc_course\/7538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/mooc_course"}],"about":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/types\/mooc_course"}],"wp:attachment":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/media?parent=7538"}],"wp:term":[{"taxonomy":"mooc_category","embeddable":true,"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/mooc_category?post=7538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}