{"id":7403,"date":"2026-03-04T12:11:03","date_gmt":"2026-03-04T12:11:03","guid":{"rendered":"https:\/\/educaedtech.foundation\/moocs\/mobility-as-a-service-ineco\/"},"modified":"2026-03-04T12:11:03","modified_gmt":"2026-03-04T12:11:03","slug":"mobility-as-a-service-ineco","status":"publish","type":"mooc_course","link":"https:\/\/educaedtech.foundation\/en\/moocs\/mobility-as-a-service-ineco\/","title":{"rendered":"Mobility as a service (Ineco)"},"content":{"rendered":"<p>El curso <strong>Mobility as a Service (Ineco)<\/strong> te ofrece la oportunidad de adentrarte en un sector en <strong>pleno auge<\/strong>, donde la <strong>integraci\u00f3n de servicios de movilidad<\/strong> se convierte en <strong>clave<\/strong> para el <strong>desarrollo urbano sostenible<\/strong>. La creciente demanda de <strong>expertos<\/strong> en este \u00e1mbito genera un sinf\u00edn de <strong>oportunidades laborales<\/strong>, posicion\u00e1ndote a la <strong>vanguardia<\/strong> de la <strong>innovaci\u00f3n en transporte<\/strong>. A lo largo de este curso, adquirir\u00e1s <strong>habilidades esenciales<\/strong> para comprender y gestionar <strong>ecosistemas de movilidad<\/strong> que combinan <strong>tecnolog\u00eda<\/strong> y <strong>servicios<\/strong>, transformando la manera en que las personas se <strong>desplazan<\/strong>. Descubre c\u00f3mo puedes ser parte de la <strong>revoluci\u00f3n del transporte<\/strong>, dise\u00f1ando <strong>soluciones<\/strong> que no solo mejoran la <strong>eficiencia<\/strong>, sino que tambi\u00e9n contribuyen a una sociedad m\u00e1s <strong>conectada<\/strong> y <strong>accesible<\/strong>. Tu participaci\u00f3n en este curso no solo te prepara para enfrentar los <strong>desaf\u00edos actuales<\/strong>, sino que tambi\u00e9n te sit\u00faa como un <strong>pionero<\/strong> en el <strong>futuro de la movilidad<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>El curso Mobility as a Service (Ineco) est\u00e1 dirigido a profesionales y titulados del sector del transporte y la movilidad que deseen ampliar o actualizar sus conocimientos sobre las \u00faltimas tendencias y tecnolog\u00edas en servicios de movilidad. Ideal para aquellos interesados en integrar soluciones innovadoras en sus proyectos actuales.<\/p>","protected":false},"featured_media":0,"template":"","mooc_category":[40,135,136],"class_list":["post-7403","mooc_course","type-mooc_course","status-publish","hentry","mooc_category-group-corporativo","mooc_category-area-35","mooc_category-academy-1182"],"acf":[],"_links":{"self":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/mooc_course\/7403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/mooc_course"}],"about":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/types\/mooc_course"}],"wp:attachment":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/media?parent=7403"}],"wp:term":[{"taxonomy":"mooc_category","embeddable":true,"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/mooc_category?post=7403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}