{"id":7390,"date":"2026-03-04T12:11:00","date_gmt":"2026-03-04T12:11:00","guid":{"rendered":"https:\/\/educaedtech.foundation\/moocs\/plan-de-igualdad-2024-2027-cogersa\/"},"modified":"2026-03-04T12:11:00","modified_gmt":"2026-03-04T12:11:00","slug":"plan-de-igualdad-2024-2027-cogersa","status":"publish","type":"mooc_course","link":"https:\/\/educaedtech.foundation\/en\/moocs\/plan-de-igualdad-2024-2027-cogersa\/","title":{"rendered":"Plan de Igualdad 2024-2027. COGERSA"},"content":{"rendered":"<p>El curso <strong>Plan de Igualdad 2024-2027. COGERSA<\/strong> es tu oportunidad para adentrarte en un <strong>\u00e1mbito en pleno auge<\/strong> y de <strong>vital relevancia<\/strong> en la <strong>sociedad actual<\/strong>. La <strong>igualdad de g\u00e9nero<\/strong> es un tema que gana cada vez m\u00e1s <strong>atenci\u00f3n<\/strong> y <strong>urgencia<\/strong>, y formarte en este campo te posiciona como un <strong>agente de cambio<\/strong> en la b\u00fasqueda de una sociedad m\u00e1s <strong>justa<\/strong> y <strong>equitativa<\/strong>.<\/p>\n<p>Este curso te proporcionar\u00e1 <strong>herramientas clave<\/strong> para <strong>comprender y aplicar principios de igualdad<\/strong> en diversos <strong>contextos laborales y sociales<\/strong>, desarrollando <strong>habilidades cr\u00edticas<\/strong> para el <strong>an\u00e1lisis<\/strong> y la <strong>implementaci\u00f3n de pol\u00edticas de igualdad<\/strong>.<\/p>\n<p>Adem\u00e1s, la <strong>modalidad online<\/strong> te ofrece la <strong>flexibilidad<\/strong> para <strong>aprender a tu ritmo<\/strong> y desde <strong>cualquier lugar<\/strong>, facilitando una <strong>formaci\u00f3n accesible<\/strong> y adaptada a tus <strong>necesidades<\/strong>.<\/p>\n<p>Participar en este curso no solo <strong>enriquecer\u00e1 tu perfil profesional<\/strong>, sino que tambi\u00e9n te permitir\u00e1 <strong>contribuir activamente<\/strong> a un <strong>cambio positivo y necesario<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>El curso Plan de Igualdad 2024-2027. COGERSA est\u00e1 dirigido a profesionales y titulados del sector interesados en profundizar y actualizar sus conocimientos en pol\u00edticas de igualdad. Ideal para quienes buscan entender mejor la implementaci\u00f3n de medidas inclusivas y promover un entorno laboral m\u00e1s equitativo, sin requerir experiencia previa avanzada en el tema.<\/p>","protected":false},"featured_media":0,"template":"","mooc_category":[40,135,136],"class_list":["post-7390","mooc_course","type-mooc_course","status-publish","hentry","mooc_category-group-corporativo","mooc_category-area-35","mooc_category-academy-1182"],"acf":[],"_links":{"self":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/mooc_course\/7390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/mooc_course"}],"about":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/types\/mooc_course"}],"wp:attachment":[{"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/media?parent=7390"}],"wp:term":[{"taxonomy":"mooc_category","embeddable":true,"href":"https:\/\/educaedtech.foundation\/en\/wp-json\/wp\/v2\/mooc_category?post=7390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}